{"id":725,"count":1,"description":"","link":"https:\/\/themedicalxchange.com\/en\/tag\/select\/","name":"SELECT","slug":"select","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SELECT Archives - The Medical Xchange<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/themedicalxchange.com\/en\/tag\/select\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SELECT Archives - The Medical Xchange\" \/>\n<meta property=\"og:url\" content=\"https:\/\/themedicalxchange.com\/en\/tag\/select\/\" \/>\n<meta property=\"og:site_name\" content=\"The Medical Xchange\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/themedicalxchange.com\\\/en\\\/tag\\\/select\\\/\",\"url\":\"https:\\\/\\\/themedicalxchange.com\\\/en\\\/tag\\\/select\\\/\",\"name\":\"SELECT Archives - The Medical Xchange\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/themedicalxchange.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/themedicalxchange.com\\\/en\\\/tag\\\/select\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/themedicalxchange.com\\\/en\\\/tag\\\/select\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/themedicalxchange.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SELECT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/themedicalxchange.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/themedicalxchange.com\\\/en\\\/\",\"name\":\"The Medical Xchange\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/themedicalxchange.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SELECT Archives - The Medical Xchange","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/themedicalxchange.com\/en\/tag\/select\/","og_locale":"en_US","og_type":"article","og_title":"SELECT Archives - The Medical Xchange","og_url":"https:\/\/themedicalxchange.com\/en\/tag\/select\/","og_site_name":"The Medical Xchange","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/themedicalxchange.com\/en\/tag\/select\/","url":"https:\/\/themedicalxchange.com\/en\/tag\/select\/","name":"SELECT Archives - The Medical Xchange","isPartOf":{"@id":"https:\/\/themedicalxchange.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/themedicalxchange.com\/en\/tag\/select\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/themedicalxchange.com\/en\/tag\/select\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/themedicalxchange.com\/en\/"},{"@type":"ListItem","position":2,"name":"SELECT"}]},{"@type":"WebSite","@id":"https:\/\/themedicalxchange.com\/en\/#website","url":"https:\/\/themedicalxchange.com\/en\/","name":"The Medical Xchange","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/themedicalxchange.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/themedicalxchange.com\/en\/wp-json\/wp\/v2\/tags\/725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/themedicalxchange.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/themedicalxchange.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/themedicalxchange.com\/en\/wp-json\/wp\/v2\/posts?tags=725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}