{"id":12468,"date":"2017-04-04T15:48:56","date_gmt":"2017-04-04T19:48:56","guid":{"rendered":"https:\/\/themedicalxchange.com\/wp-content\/uploads\/2014\/05\/EX_7008_DDW_Crohns_Fig_1.PNG"},"modified":"2021-08-02T15:57:06","modified_gmt":"2021-08-02T19:57:06","slug":"ex_7008_ddw_crohns_fig-1","status":"inherit","type":"attachment","link":"https:\/\/themedicalxchange.com\/fr\/2014\/05\/23\/semaine-des-maladies-digestives-de-2014-digestiv-3\/ex_7008_ddw_crohns_fig-1\/","title":{"rendered":"EX_7008_DDW_Crohns_Fig 1"},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-12468","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EX_7008_DDW_Crohns_Fig 1 - The Medical Xchange<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/themedicalxchange.com\/wp-content\/uploads\/2014\/05\/EX_7008_DDW_Crohns_Fig_1.PNG\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EX_7008_DDW_Crohns_Fig 1 - The Medical Xchange\" \/>\n<meta property=\"og:url\" content=\"https:\/\/themedicalxchange.com\/wp-content\/uploads\/2014\/05\/EX_7008_DDW_Crohns_Fig_1.PNG\" \/>\n<meta property=\"og:site_name\" content=\"The Medical Xchange\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-02T19:57:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/themedicalxchange.com\/wp-content\/uploads\/2014\/05\/EX_7008_DDW_Crohns_Fig_1.PNG\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/themedicalxchange.com\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/EX_7008_DDW_Crohns_Fig_1.PNG\",\"url\":\"https:\\\/\\\/themedicalxchange.com\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/EX_7008_DDW_Crohns_Fig_1.PNG\",\"name\":\"EX_7008_DDW_Crohns_Fig 1 - The Medical Xchange\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/themedicalxchange.com\\\/en\\\/#website\"},\"datePublished\":\"2017-04-04T19:48:56+00:00\",\"dateModified\":\"2021-08-02T19:57:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/themedicalxchange.com\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/EX_7008_DDW_Crohns_Fig_1.PNG#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/themedicalxchange.com\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/EX_7008_DDW_Crohns_Fig_1.PNG\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/themedicalxchange.com\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/EX_7008_DDW_Crohns_Fig_1.PNG#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/themedicalxchange.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Des donn\u00e9es issues de l\u2019essai IMAgINE 1 : l\u2019utilisation des agents biologiques contre la maladie de Crohn chez les enfants\",\"item\":\"https:\\\/\\\/themedicalxchange.com\\\/fr\\\/2014\\\/05\\\/23\\\/semaine-des-maladies-digestives-de-2014-digestiv-3\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"EX_7008_DDW_Crohns_Fig 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/themedicalxchange.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/themedicalxchange.com\\\/en\\\/\",\"name\":\"The Medical Xchange\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/themedicalxchange.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EX_7008_DDW_Crohns_Fig 1 - The Medical Xchange","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/themedicalxchange.com\/wp-content\/uploads\/2014\/05\/EX_7008_DDW_Crohns_Fig_1.PNG","og_locale":"fr_FR","og_type":"article","og_title":"EX_7008_DDW_Crohns_Fig 1 - The Medical Xchange","og_url":"https:\/\/themedicalxchange.com\/wp-content\/uploads\/2014\/05\/EX_7008_DDW_Crohns_Fig_1.PNG","og_site_name":"The Medical Xchange","article_modified_time":"2021-08-02T19:57:06+00:00","og_image":[{"width":960,"height":720,"url":"https:\/\/themedicalxchange.com\/wp-content\/uploads\/2014\/05\/EX_7008_DDW_Crohns_Fig_1.PNG","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/themedicalxchange.com\/wp-content\/uploads\/2014\/05\/EX_7008_DDW_Crohns_Fig_1.PNG","url":"https:\/\/themedicalxchange.com\/wp-content\/uploads\/2014\/05\/EX_7008_DDW_Crohns_Fig_1.PNG","name":"EX_7008_DDW_Crohns_Fig 1 - The Medical Xchange","isPartOf":{"@id":"https:\/\/themedicalxchange.com\/en\/#website"},"datePublished":"2017-04-04T19:48:56+00:00","dateModified":"2021-08-02T19:57:06+00:00","breadcrumb":{"@id":"https:\/\/themedicalxchange.com\/wp-content\/uploads\/2014\/05\/EX_7008_DDW_Crohns_Fig_1.PNG#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/themedicalxchange.com\/wp-content\/uploads\/2014\/05\/EX_7008_DDW_Crohns_Fig_1.PNG"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/themedicalxchange.com\/wp-content\/uploads\/2014\/05\/EX_7008_DDW_Crohns_Fig_1.PNG#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/themedicalxchange.com\/en\/"},{"@type":"ListItem","position":2,"name":"Des donn\u00e9es issues de l\u2019essai IMAgINE 1 : l\u2019utilisation des agents biologiques contre la maladie de Crohn chez les enfants","item":"https:\/\/themedicalxchange.com\/fr\/2014\/05\/23\/semaine-des-maladies-digestives-de-2014-digestiv-3\/"},{"@type":"ListItem","position":3,"name":"EX_7008_DDW_Crohns_Fig 1"}]},{"@type":"WebSite","@id":"https:\/\/themedicalxchange.com\/en\/#website","url":"https:\/\/themedicalxchange.com\/en\/","name":"The Medical Xchange","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/themedicalxchange.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/themedicalxchange.com\/wp-content\/uploads\/2014\/05\/EX_7008_DDW_Crohns_Fig_1.PNG'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/themedicalxchange.com\/wp-content\/uploads\/2014\/05\/EX_7008_DDW_Crohns_Fig_1-300x225.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/themedicalxchange.com\/wp-content\/uploads\/2014\/05\/EX_7008_DDW_Crohns_Fig_1-300x225.png 300w, https:\/\/themedicalxchange.com\/wp-content\/uploads\/2014\/05\/EX_7008_DDW_Crohns_Fig_1-768x576.png 768w, https:\/\/themedicalxchange.com\/wp-content\/uploads\/2014\/05\/EX_7008_DDW_Crohns_Fig_1-800x600.png 800w, https:\/\/themedicalxchange.com\/wp-content\/uploads\/2014\/05\/EX_7008_DDW_Crohns_Fig_1.PNG 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":960,"height":720,"file":"2014\/05\/EX_7008_DDW_Crohns_Fig_1.PNG","sizes":{"thumbnail":{"file":"EX_7008_DDW_Crohns_Fig_1-150x150.png","width":150,"height":150,"mime_type":"image\/png","source_url":"https:\/\/themedicalxchange.com\/wp-content\/uploads\/2014\/05\/EX_7008_DDW_Crohns_Fig_1-150x150.png"},"medium":{"file":"EX_7008_DDW_Crohns_Fig_1-300x225.png","width":300,"height":225,"mime_type":"image\/png","source_url":"https:\/\/themedicalxchange.com\/wp-content\/uploads\/2014\/05\/EX_7008_DDW_Crohns_Fig_1-300x225.png"},"medium_large":{"file":"EX_7008_DDW_Crohns_Fig_1-768x576.png","width":768,"height":576,"mime_type":"image\/png","source_url":"https:\/\/themedicalxchange.com\/wp-content\/uploads\/2014\/05\/EX_7008_DDW_Crohns_Fig_1-768x576.png"},"post-thumbnail":{"file":"EX_7008_DDW_Crohns_Fig_1-800x600.png","width":800,"height":600,"mime_type":"image\/png","source_url":"https:\/\/themedicalxchange.com\/wp-content\/uploads\/2014\/05\/EX_7008_DDW_Crohns_Fig_1-800x600.png"},"elearning":{"file":"EX_7008_DDW_Crohns_Fig_1-700x393.png","width":700,"height":393,"mime_type":"image\/png","source_url":"https:\/\/themedicalxchange.com\/wp-content\/uploads\/2014\/05\/EX_7008_DDW_Crohns_Fig_1-700x393.png"},"full":{"file":"EX_7008_DDW_Crohns_Fig_1.PNG","width":960,"height":720,"mime_type":"image\/png","source_url":"https:\/\/themedicalxchange.com\/wp-content\/uploads\/2014\/05\/EX_7008_DDW_Crohns_Fig_1.PNG"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":5027,"source_url":"https:\/\/themedicalxchange.com\/wp-content\/uploads\/2014\/05\/EX_7008_DDW_Crohns_Fig_1.PNG","_links":{"self":[{"href":"https:\/\/themedicalxchange.com\/fr\/wp-json\/wp\/v2\/media\/12468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/themedicalxchange.com\/fr\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/themedicalxchange.com\/fr\/wp-json\/wp\/v2\/types\/attachment"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":5027,"href":"https:\/\/themedicalxchange.com\/fr\/wp-json\/wp\/v2\/posts\/5027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}